{"id":85,"date":"2023-06-10T20:14:46","date_gmt":"2023-06-11T01:14:46","guid":{"rendered":"https:\/\/uniqhomesrealestateagency.com\/?page_id=85"},"modified":"2023-06-12T12:54:33","modified_gmt":"2023-06-12T17:54:33","slug":"contacto","status":"publish","type":"page","link":"https:\/\/uniqhomesrealestateagency.com\/index.php\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"\n\n<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-82-block-852b2267-f87b-47d8-a82d-aa614832f226\">\n\t\t\t\t#wpforms-82.wpforms-block-852b2267-f87b-47d8-a82d-aa614832f226 {\n\t\t\t\t\t--wpforms-field-border-color: #022913;\n--wpforms-field-text-color: #022913;\n--wpforms-button-background-color: #022913;\n--wpforms-button-text-color: #F6F6F6;\n--wpforms-button-size-font-size: 20px;\n--wpforms-button-size-height: 48px;\n--wpforms-button-size-padding-h: 20px;\n--wpforms-button-size-margin-top: 15px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-852b2267-f87b-47d8-a82d-aa614832f226 wpwpformsform-selector clientId59618933-6e97-4a86-83b2-c045e6af3889formId82copyPasteValueu0022displayTitleu0022falseu0022displayDescu0022falseu0022fieldSizeu0022u0022mediumu0022u0022fieldBorderRadiusu0022u00223pxu0022u0022fieldBackgroundColoru0022u0022ffffffu0022u0022fieldBorderColoru0022u0022rgba 0 025 u0022u0022fieldTextColoru0022u0022rgba 07 u0022u0022labelSizeu0022u0022mediumu0022u0022labelColoru0022u0022c6a140u0022u0022labelSublabelColoru0022u0022rgba 055 u0022u0022labelErrorColoru0022u0022d63637u0022u0022buttonSizeu0022u0022mediumu0022u0022buttonBorderRadiusu0022u00223pxu0022u0022buttonBackgroundColoru0022u0022066aabu0022u0022buttonTextColoru0022u0022ffffffu0022  wpforms-render-modern\" id=\"wpforms-82\"><form id=\"wpforms-form-82\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"82\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/85\" data-token=\"e3dbca87f941a81a350083a721148d8d\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-82-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-82-field_7\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-82-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-82-field_7-error\" required><\/div><div id=\"wpforms-82-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-82-field_1\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-82-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-82-field_1-error\" required><\/div><div id=\"wpforms-82-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-82-field_3\">Tel\u00e9fono <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-82-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-82-field_3-error\" required><\/div><div id=\"wpforms-82-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-82-field_4\">Comentario <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-82-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-82-field_4-error\" required><\/textarea><\/div><div id=\"wpforms-82-field_5-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"5\"><fieldset><legend class=\"wpforms-field-label\">Casillas de verificaci\u00f3n <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-82-field_5\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-82-field_5_1\" name=\"wpforms[fields][5][]\" value=\"Acepto la pol\u00edtica de privacidad\" aria-errormessage=\"wpforms-82-field_5_1-error\" aria-describedby=\"wpforms-82-field_5-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-82-field_5_1\">Acepto la pol\u00edtica de privacidad<\/label><\/li><\/ul><div id=\"wpforms-82-field_5-description\" class=\"wpforms-field-description\">Haz clic en el siguiente <a href='https:\/\/uniqhomesrealestateagency.com\/index.php\/pol\u00edtica-privacidad\/(abre en una nueva pesta\u00f1a)'> enlace<\/a> para ver los t\u00e9rminos completos de la pol\u00edtica de privacidad.<\/div><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"82\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-82\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/uniqhomesrealestateagency.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/pages\/85"}],"collection":[{"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":12,"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/pages\/85\/revisions"}],"predecessor-version":[{"id":189,"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/pages\/85\/revisions\/189"}],"wp:attachment":[{"href":"https:\/\/uniqhomesrealestateagency.com\/index.php\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}